{"id":6055,"count":456,"description":"","link":"https:\/\/www.sabguru.com\/news\/category\/world-hindi-news\/world-political-news\/","name":"World Political","slug":"world-political-news","taxonomy":"category","parent":2530,"meta":[],"_links":{"self":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/categories\/6055"}],"collection":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/categories\/2530"}],"wp:post_type":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/posts?categories=6055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}