{"id":3718,"date":"2014-11-06T09:04:11","date_gmt":"2014-11-06T03:34:11","guid":{"rendered":"https:\/\/www.sabguru.com\/?p=3718"},"modified":"2014-11-06T09:04:11","modified_gmt":"2014-11-06T03:34:11","slug":"man-was-murdered-by-friend-over-money-in-vapi","status":"publish","type":"post","link":"https:\/\/www.sabguru.com\/news\/man-was-murdered-by-friend-over-money-in-vapi\/","title":{"rendered":"\u0926\u094b\u0938\u094d\u0924 \u0939\u0940 \u0928\u093f\u0915\u0932\u093e \u0939\u0924\u094d\u092f\u093e\u0930\u093e, \u0932\u093e\u0932\u091a \u092e\u0947\u0902 \u092e\u093f\u0924\u094d\u0930 \u0915\u093e \u0917\u0932\u093e \u0930\u0947\u0924\u093e"},"content":{"rendered":"<figure id=\"attachment_3719\" aria-describedby=\"caption-attachment-3719\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-3719\" src=\"https:\/\/www.sabguru.com\/wp-content\/uploads\/2014\/11\/murder.jpg\" alt=\"murder\" width=\"600\" height=\"350\" srcset=\"https:\/\/www.sabguru.com\/wp-content\/uploads\/2014\/11\/murder.jpg 600w, https:\/\/www.sabguru.com\/wp-content\/uploads\/2014\/11\/murder-300x175.jpg 300w, https:\/\/www.sabguru.com\/wp-content\/uploads\/2014\/11\/murder-500x291.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-3719\" class=\"wp-caption-text\">man was murdered by friend over money in vapi<\/figcaption><\/figure>\n<p>\u0935\u093e\u092a\u0940\u0964 \u0915\u094b\u091a\u0930\u0935\u093e \u092e\u0947\u0902 23 \u0905\u0915\u094d\u091f\u0942\u092c\u0930 \u0915\u0940 \u0930\u093e\u0924 \u0915\u094b \u0930\u0941\u092a\u090f \u0915\u0947 \u0932\u093e\u0932\u091a \u092e\u0947\u0902 \u090f\u0915 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0928\u0947 \u0905\u092a\u0928\u0947 \u0939\u0940 \u0926\u094b\u0938\u094d\u0924 \u0915\u0940 \u0939\u0924\u094d\u092f\u093e \u0915\u0930 \u0926\u0940\u0964 \u0939\u0924\u094d\u092f\u093e \u0915\u0930\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u0930\u0941\u092a\u090f \u0914\u0930 \u092e\u094b\u092c\u093e\u0907\u0932 \u0932\u0947\u0915\u0930\u00a0 \u092b\u0930\u093e\u0930 \u0906\u0930\u094b\u092a\u0940 \u0915\u094b \u092a\u0941\u0932\u093f\u0938 \u0928\u0947 \u0906\u0916\u093f\u0930\u0915\u093e\u0930 \u0915\u093e\u0932 \u0921\u093f\u091f\u0947\u0932 \u0915\u0947 \u0906\u0927\u093e\u0930 \u092a\u0930 \u0917\u093f\u0930\u092b\u094d\u0924\u093e\u0930 \u0915\u0930 \u0932\u093f\u092f\u093e\u0964&#8230;<!--more--><br \/>\n\u091c\u093e\u0928\u0915\u093e\u0930\u0940 \u0915\u0947 \u092e\u0941\u0924\u093e\u092c\u093f\u0915 24 \u0905\u0915\u094d\u091f\u0942\u092c\u0930 \u0915\u0940 \u0938\u0941\u092c\u0939 \u0915\u094b\u091a\u0930\u0935\u093e \u0917\u093e\u0902\u0935 \u092e\u0947\u0902 \u0928\u0939\u0930 \u0915\u093f\u0928\u093e\u0930\u0947 \u091a\u093f\u092e\u0928 \u092a\u091f\u0947\u0932 \u0915\u0940 \u091a\u093e\u0932 \u092e\u0947\u0902 \u0930\u0939\u0928\u0947 \u0935\u093e\u0932\u0947 \u0938\u0941\u0916\u0926\u0947\u0935 \u0915\u094b\u0930\u0940 \u0915\u093e \u0936\u0935 \u0909\u0938\u0915\u0947 \u0915\u092e\u0930\u0947 \u092e\u0947\u0902 \u092e\u093f\u0932\u093e\u00a0 \u0925\u093e\u0964 \u092a\u0941\u0932\u093f\u0938 \u0928\u0947 \u092e\u0943\u0924\u0915 \u0938\u0941\u0916\u0926\u0947\u0935 \u0915\u094b\u0930\u0940 \u0915\u0947 \u092e\u094b\u092c\u093e\u0907\u0932 \u0928\u0902\u092c\u0930 \u0915\u0940 \u0921\u093f\u091f\u0947\u0932 \u0928\u093f\u0915\u093e\u0932\u0915\u0930 \u091c\u093e\u0902\u091a \u0936\u0941\u0930\u0941 \u0915\u0940 \u0924\u094b \u0918\u091f\u0928\u093e \u0935\u093e\u0932\u0940 \u0930\u093e\u0924 \u0938\u0924\u094d\u092f\u0928\u093e\u0930\u093e\u092f\u0923 \u0935\u093f\u0936\u094d\u0935\u0915\u0930\u094d\u092e\u093e \u0915\u0947 \u0928\u0902\u092c\u0930 \u0938\u0947 \u092c\u093e\u0924 \u0939\u094b\u0928\u0947 \u0915\u0940 \u091c\u093e\u0928\u0915\u093e\u0930\u0940 \u0938\u093e\u092e\u0928\u0947 \u0906\u0908\u0964 \u0936\u0902\u0915\u093e \u0915\u0947 \u0906\u0927\u093e\u0930 \u092a\u0930 \u092a\u0941\u0932\u093f\u0938 \u0928\u0947 \u0938\u0924\u094d\u092f\u0928\u093e\u0930\u093e\u092f\u0923 \u0915\u094b \u0917\u093f\u0930\u092b\u094d\u0924 \u092e\u0947\u0902 \u0932\u0947\u0915\u0930 \u092a\u0942\u091b\u0924\u093e\u091b \u0915\u0940 \u0924\u094b \u0909\u0938\u0928\u0947 \u0939\u0924\u094d\u092f\u093e \u0915\u0940 \u092c\u093e\u0924 \u0915\u092c\u0942\u0932 \u0915\u0930\u0924\u0947 \u0939\u0941\u090f \u092c\u0924\u093e\u092f\u093e \u0915\u093f \u0930\u0941\u092a\u090f \u0915\u0940 \u0932\u093e\u0932\u091a \u092e\u0947\u0902 \u092f\u0939 \u0905\u092a\u0930\u093e\u0927 \u0915\u093f\u092f\u093e \u0939\u0948\u0964<br \/>\n\u0916\u0941\u0936\u0940 \u092e\u0947\u0902 \u0936\u093e\u092e\u093f\u0932 \u0915\u0930\u0928\u093e \u092a\u0921\u093c\u093e \u092e\u0939\u0902\u0917\u093e<br \/>\n\u092a\u0941\u0932\u093f\u0938 \u091c\u093e\u0902\u091a \u092e\u0947\u0902 \u0938\u093e\u092e\u0928\u0947 \u0906\u092f\u093e \u0915\u093f \u090f\u0915 \u092a\u0947\u092a\u0930\u092e\u093f\u0932 \u092e\u0947\u0902 \u0915\u093e\u092e \u0915\u0930\u0928\u0947 \u0935\u093e\u0932\u0947 \u0938\u0941\u0916\u0926\u0947\u0935 \u0915\u094b \u0935\u0947\u0924\u0928 \u0914\u0930 \u092c\u094b\u0928\u0938 \u092e\u093f\u0932\u093e\u0915\u0930 \u0915\u0930\u0940\u092c 20 \u0939\u091c\u093e\u0930 \u0930\u0941\u092a\u090f \u092e\u093f\u0932\u0947 \u0925\u0947\u0964 \u0907\u0938\u0915\u0940 \u0916\u0941\u0936\u0940 \u092e\u0947\u0902 \u0909\u0938\u0928\u0947 \u0915\u094b\u091a\u0930\u0935\u093e \u092e\u0947\u0902 \u0939\u0940 \u0928\u0930\u0947\u0936 \u092a\u091f\u0947\u0932 \u0915\u0940 \u091a\u093e\u0932 \u092e\u0947\u0902 \u0930\u0939\u0928\u0947 \u0935\u093e\u0932\u0947 \u0938\u0924\u094d\u092f\u0928\u093e\u0930\u093e\u092f\u0923 \u0935\u093f\u0936\u094d\u0935\u0915\u0930\u094d\u092e\u093e \u0915\u094b \u0926\u0940\u092a\u093e\u0935\u0932\u0940 \u0935\u093e\u0932\u0940 \u0930\u093e\u0924 \u0905\u092a\u0928\u0947 \u0918\u0930 \u0936\u0930\u093e\u092c \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u093e \u0928\u094d\u092f\u094b\u0924\u093e \u0926\u093f\u092f\u093e\u0964 \u0938\u0941\u0916\u0926\u0947\u0935 \u0905\u0915\u0947\u0932\u093e \u0930\u0939\u0924\u093e \u0925\u093e, \u0932\u093f\u0939\u093e\u091c\u093e \u0936\u0930\u093e\u092c \u092a\u093e\u0930\u094d\u091f\u0940 \u0915\u093e \u0928\u093f\u092e\u0902\u0924\u094d\u0930\u0923 \u092a\u093e\u0924\u0947 \u0939\u0940 \u0938\u0924\u094d\u092f\u0928\u093e\u0930\u093e\u0923 \u0915\u0947 \u0926\u093f\u092e\u093e\u0917 \u092e\u0947\u0902 \u0939\u0924\u094d\u092f\u093e \u0915\u093e \u0935\u093f\u091a\u093e\u0930 \u0906\u092f\u093e\u0964<\/p>\n<p>\u0915\u093e\u0930\u0928\u093e\u092e\u0947 \u0915\u094b \u0905\u0902\u091c\u093e\u092e \u0926\u0947\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0906\u0930\u094b\u092a\u0940 \u0928\u0947 \u092a\u0942\u0930\u0940 \u092f\u094b\u091c\u0928\u093e \u092c\u0928\u093e\u0908 \u0914\u0930 \u0909\u0938\u0915\u0947 \u0918\u0930 \u091c\u093e\u0924\u0947 \u0938\u092e\u092f \u0915\u094b\u0932\u094d\u0921\u0921\u094d\u0930\u093f\u0902\u0915 \u0915\u0940 \u092c\u094b\u0924\u0932 \u0932\u0947 \u0932\u0940\u0964 \u0938\u0941\u0916\u0926\u0947\u0935 \u0915\u0947 \u0918\u0930 \u092a\u0939\u0941\u0902\u091a\u0915\u0930 \u0909\u0938\u0928\u0947 \u0905\u092a\u0928\u0947 \u0917\u093f\u0932\u093e\u0938 \u092e\u0947\u0902 \u0915\u094b\u0932\u094d\u0921\u0921\u094d\u0930\u093f\u0902\u0915 \u091c\u094d\u092f\u093e\u0926\u093e \u0921\u093e\u0932\u0940 \u0914\u0930 \u0938\u0941\u0916\u0926\u0947\u0935 \u0915\u094b \u091c\u094d\u092f\u093e\u0926\u093e \u0936\u0930\u093e\u092c \u092a\u093f\u0932\u093e\u0908\u0964 \u0936\u0930\u093e\u092c \u092a\u0940\u0915\u0930 \u091c\u092c \u0938\u0941\u0916\u0926\u0947\u0935 \u0928\u0936\u0947 \u092e\u0947\u0902 \u091a\u0942\u0930 \u0939\u094b \u0917\u092f\u093e \u0924\u094b \u0909\u0938\u0915\u093e \u0917\u0932\u093e \u0930\u0947\u0924 \u0926\u093f\u092f\u093e\u0964<br \/>\n15 \u0930\u0941\u092a\u090f \u0915\u0947 \u091a\u093e\u0915\u0942 \u0938\u0947 \u0932\u0940 \u091c\u093e\u0928<br \/>\n\u092a\u0941\u0932\u093f\u0938 \u091c\u093e\u0902\u091a \u092e\u0947\u0902 \u0938\u093e\u092e\u0928\u0947 \u0906\u092f\u093e \u0939\u0948 \u0915\u093f \u0938\u0941\u0916\u0926\u0947\u0935 \u0915\u0947 \u0918\u0930 \u091c\u093e\u0928\u0947 \u0938\u0947 \u092a\u0942\u0930\u094d\u0935 \u0909\u0938\u0928\u0947 \u0915\u094b\u091a\u0930\u0935\u093e \u092e\u0947\u0902 \u0926\u0941\u0915\u093e\u0928\u0926\u093e\u0930 \u0930\u092e\u0947\u0936 \u092a\u091f\u0947\u0932 \u0915\u0940 \u0926\u0941\u0915\u093e\u0928 \u0938\u0947 15 \u0930\u0941\u092a\u090f \u0915\u093e \u0938\u092c\u094d\u091c\u0940 \u0915\u093e\u091f\u0928\u0947 \u0935\u093e\u0932\u093e \u091a\u093e\u0915\u0942 \u0916\u0930\u0940\u0926\u093e \u0925\u093e\u0964 \u0909\u0938\u0940 \u091a\u093e\u0915\u0942 \u0938\u0947 \u0909\u0938\u0928\u0947 \u0938\u0941\u0916\u0926\u0947\u0935 \u0915\u0940 \u091c\u093e\u0928 \u0932\u0940\u0964 \u092a\u0941\u0932\u093f\u0938 \u0928\u0947 \u092c\u0924\u093e\u092f\u093e \u0915\u093f \u0939\u0924\u094d\u092f\u093e \u0935\u093e\u0932\u0940 \u0935\u093e\u0932\u0940 \u0930\u093e\u0924 \u0909\u0938\u0928\u0947 \u0936\u093e\u092e \u0938\u093e\u0924 \u092c\u091c\u0947 \u0938\u0947 \u0930\u093e\u0924 \u0928\u094c \u092c\u091c\u0947 \u0915\u0947 \u092c\u0940\u091a \u091a\u093e\u0930 \u092c\u093e\u0930 \u092b\u094b\u0928 \u0915\u093f\u092f\u093e \u0925\u093e\u0964<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0935\u093e\u092a\u0940\u0964 \u0915\u094b\u091a\u0930\u0935\u093e \u092e\u0947\u0902 23 \u0905\u0915\u094d\u091f\u0942\u092c\u0930 \u0915\u0940 \u0930\u093e\u0924 \u0915\u094b \u0930\u0941\u092a\u090f \u0915\u0947 \u0932\u093e\u0932\u091a \u092e\u0947\u0902 \u090f\u0915 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0928\u0947 \u0905\u092a\u0928\u0947 \u0939\u0940 \u0926\u094b\u0938\u094d\u0924 \u0915\u0940 \u0939\u0924\u094d\u092f\u093e \u0915\u0930 \u0926\u0940\u0964 \u0939\u0924\u094d\u092f\u093e \u0915\u0930\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u0930\u0941\u092a\u090f \u0914\u0930 \u092e\u094b\u092c\u093e\u0907\u0932 \u0932\u0947\u0915\u0930\u00a0 \u092b\u0930\u093e\u0930 \u0906\u0930\u094b\u092a\u0940 \u0915\u094b \u092a\u0941\u0932\u093f\u0938 \u0928\u0947 \u0906\u0916\u093f\u0930\u0915\u093e\u0930 \u0915\u093e\u0932 \u0921\u093f\u091f\u0947\u0932 \u0915\u0947 \u0906\u0927\u093e\u0930 \u092a\u0930 \u0917\u093f\u0930\u092b\u094d\u0924\u093e\u0930 \u0915\u0930 \u0932\u093f\u092f\u093e\u0964&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12,14461,1545,15800],"tags":[3932,1657,82,918],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/posts\/3718"}],"collection":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/comments?post=3718"}],"version-history":[{"count":0,"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/posts\/3718\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/media?parent=3718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/categories?post=3718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sabguru.com\/news\/wp-json\/wp\/v2\/tags?post=3718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}